{"id":12499,"date":"2022-05-10T10:33:40","date_gmt":"2022-05-10T08:33:40","guid":{"rendered":"https:\/\/strtgy.design\/?post_type=evento&#038;p=12499"},"modified":"2023-08-17T18:07:28","modified_gmt":"2023-08-17T16:07:28","slug":"design-economy-2022-con-domenico-sturabotti","status":"publish","type":"evento","link":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/","title":{"rendered":"Design Economy 2022"},"content":{"rendered":"<h3>Di cosa si tratta<\/h3>\n<p><b>Fondazione<\/b> <b>Symbola<\/b>, con Deloitte Private e Poli.Design, ha analizzato, nella 5\u00b0 edizione del <b>Rapporto Design Economy<\/b>, attraverso dati e storie, il settore del design made in Italy, evidenziando il legame tra investimenti in design e competitivit\u00e0 delle imprese.<\/p>\n<p>Nel lavoro di Symbola \u00e8 evidente che le aziende vincenti hanno una ricetta per il successo: portano il <b>Design<\/b> nel <b>processo<\/b> <b>strategico<\/b>, piuttosto che utilizzarlo come mera miglioria estetica del prodotto.<\/p>\n<p>Il rapporto Design Economy di quest\u2019anno dedica un capitolo alla relazione tra il settore italiano e la <b>sostenibilit\u00e0<\/b>, relazione alla base del nuovo Bauhaus europeo lanciato dalla Presidente von der Leyen nel 2020 per contribuire alla realizzazione del Green Deal europeo.<\/p>\n<p>In questo prezioso approfondimento si pu\u00f2 capire, finalmente, cosa succede davvero in questo settore strategico e comprendere quale sia una strada possibile per il futuro.<\/p>\n<p>Insieme a <b>Domenico<\/b> <b>Sturabotti<\/b>, direttore della Fondazione Symbola, abbiamo approfondito i dati emersi da questa nuova indagine, con uno sguardo rivolto al futuro.<\/p>\n<p>Se sei un\u0259 imprenditor\u0259, CEO, C-level, manager e vuoi capire come integrare questa funzione nei processi produttivi e strategici, non puoi non vederlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fondazione Symbola, con Deloitte Private e Poli.Design, ha analizzato, nella 5\u00b0 edizione del Rapporto Design Economy, attraverso dati e storie, il settore del design made in Italy, evidenziando il legame tra investimenti in design e competitivit\u00e0 delle imprese.<\/p>\n","protected":false},"featured_media":22472,"template":"","categories":[20,61],"tags":[],"class_list":["post-12499","evento","type-evento","status-publish","has-post-thumbnail","hentry","category-passati","category-strtgy_layout_eventi_v2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Design Economy 2022 - STRTGY<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Design Economy 2022 - STRTGY\" \/>\n<meta property=\"og:description\" content=\"Fondazione Symbola, con Deloitte Private e Poli.Design, ha analizzato, nella 5\u00b0 edizione del Rapporto Design Economy, attraverso dati e storie, il settore del design made in Italy, evidenziando il legame tra investimenti in design e competitivit\u00e0 delle imprese.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/\" \/>\n<meta property=\"og:site_name\" content=\"STRTGY\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/strtgydesign\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-17T16:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/strtgy.design\/wp-content\/uploads\/2022\/05\/Sito-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1119\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@antoniocivita\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/\",\"url\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/\",\"name\":\"Design Economy 2022 - STRTGY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Sito-9.jpg\",\"datePublished\":\"2022-05-10T08:33:40+00:00\",\"dateModified\":\"2023-08-17T16:07:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Sito-9.jpg\",\"contentUrl\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Sito-9.jpg\",\"width\":1119,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/design-economy-2022-con-domenico-sturabotti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/strtgy.design\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Design Economy 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/strtgy.design\\\/en\\\/\",\"name\":\"STRTGY\",\"description\":\"Design + Business + Tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/strtgy.design\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#organization\",\"name\":\"STRTGY\",\"url\":\"https:\\\/\\\/strtgy.design\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/STRTGY-Symbol.png\",\"contentUrl\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/STRTGY-Symbol.png\",\"width\":160,\"height\":160,\"caption\":\"STRTGY\"},\"image\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/strtgydesign\",\"https:\\\/\\\/x.com\\\/antoniocivita\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/strtgy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Design Economy 2022 - STRTGY","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/","og_locale":"en_US","og_type":"article","og_title":"Design Economy 2022 - STRTGY","og_description":"Fondazione Symbola, con Deloitte Private e Poli.Design, ha analizzato, nella 5\u00b0 edizione del Rapporto Design Economy, attraverso dati e storie, il settore del design made in Italy, evidenziando il legame tra investimenti in design e competitivit\u00e0 delle imprese.","og_url":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/","og_site_name":"STRTGY","article_publisher":"https:\/\/www.facebook.com\/strtgydesign","article_modified_time":"2023-08-17T16:07:28+00:00","og_image":[{"width":1119,"height":683,"url":"https:\/\/strtgy.design\/wp-content\/uploads\/2022\/05\/Sito-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@antoniocivita","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/","url":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/","name":"Design Economy 2022 - STRTGY","isPartOf":{"@id":"https:\/\/strtgy.design\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/#primaryimage"},"image":{"@id":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/#primaryimage"},"thumbnailUrl":"https:\/\/strtgy.design\/wp-content\/uploads\/2022\/05\/Sito-9.jpg","datePublished":"2022-05-10T08:33:40+00:00","dateModified":"2023-08-17T16:07:28+00:00","breadcrumb":{"@id":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/#primaryimage","url":"https:\/\/strtgy.design\/wp-content\/uploads\/2022\/05\/Sito-9.jpg","contentUrl":"https:\/\/strtgy.design\/wp-content\/uploads\/2022\/05\/Sito-9.jpg","width":1119,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/strtgy.design\/en\/evento\/design-economy-2022-con-domenico-sturabotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/strtgy.design\/en\/"},{"@type":"ListItem","position":2,"name":"Design Economy 2022"}]},{"@type":"WebSite","@id":"https:\/\/strtgy.design\/en\/#website","url":"https:\/\/strtgy.design\/en\/","name":"STRTGY","description":"Design + Business + Tech","publisher":{"@id":"https:\/\/strtgy.design\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strtgy.design\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/strtgy.design\/en\/#organization","name":"STRTGY","url":"https:\/\/strtgy.design\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/strtgy.design\/en\/#\/schema\/logo\/image\/","url":"https:\/\/strtgy.design\/wp-content\/uploads\/2024\/04\/STRTGY-Symbol.png","contentUrl":"https:\/\/strtgy.design\/wp-content\/uploads\/2024\/04\/STRTGY-Symbol.png","width":160,"height":160,"caption":"STRTGY"},"image":{"@id":"https:\/\/strtgy.design\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/strtgydesign","https:\/\/x.com\/antoniocivita","https:\/\/www.linkedin.com\/company\/strtgy\/"]}]}},"_links":{"self":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/evento\/12499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/types\/evento"}],"version-history":[{"count":0,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/evento\/12499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/media\/22472"}],"wp:attachment":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/media?parent=12499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/categories?post=12499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/tags?post=12499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}