{"id":21526,"date":"2023-07-17T13:06:14","date_gmt":"2023-07-17T11:06:14","guid":{"rendered":"https:\/\/strtgy.design\/?post_type=evento&#038;p=21526"},"modified":"2023-08-06T07:43:35","modified_gmt":"2023-08-06T05:43:35","slug":"the-global-state-of-okrs-2023-trends-report-edizione-italiana","status":"publish","type":"evento","link":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/","title":{"rendered":"The Global State of OKRs \u2014 2023 Trends Report \/ Edizione Italiana"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Perch\u00e9 \u00e8 importante<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gli OKR in Italia vengono visti ancora con scetticismo perch\u00e9 la maggior parte della letteratura e della formazione manageriale sull\u2019argomento viene dall\u2019estero e spesso riportata in maniera superficiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo <strong>evento interattivo<\/strong>, <strong>in lingua italiana e per il mercato italiano<\/strong>, ha lo scopo di diffondere gli apprendimenti del pi\u00f9 grande studio data-driven mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli OKR possono davvero aiutare le aziende italiane a raggiungere allineamento, prestazioni e focus sulle priorit\u00e0. Guarderemo ai risultati globali e scenderemo nei dettagli del contesto italiano sulla base dell\u2019esperienza di centinaia di ore di OKR coaching degli speaker.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cosa apprenderai<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Perch\u00e9 e come l&#8217;uso degli OKR si sta espandendo a livello globale<\/li>\n\n\n\n<li>Quali sono i principali fattori che spingono le organizzazioni a utilizzare gli OKR<\/li>\n\n\n\n<li>Qual \u00e8 la correlazione tra la maturit\u00e0 nell\u2019utilizzo degli OKR e le performance aziendali&nbsp;<\/li>\n\n\n\n<li>Quali sono le maggiori sfide nell&#8217;esecuzione della strategia e come gli OKR aiutano a risolverle<\/li>\n\n\n\n<li>Come i check-in frequenti e gli aggiornamenti sui progressi degli obiettivi influiscono sulle performance generali<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">E molto altro ancora\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La ricerca<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nel marzo 2023, <a href=\"https:\/\/quantive.com\/\">Quantive<\/a> e <a href=\"https:\/\/www.okrmentors.com\/\">OKRmentors<\/a> hanno collaborato per comprendere lo stato degli OKR e delle moderne pratiche di business agile utilizzate nelle aziende di tutto il mondo. Dopo aver intervistato oltre 400 leader aziendali in 13 Paesi, questo rapporto analizza come le organizzazioni e i leader di successo utilizzano gli OKR e le metodologie agili per migliorare i propri risultati di business.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">STRTGY \u00e8 Partner di Quantive e ha all\u2019attivo decine di programmi di implementazione OKR, in Italia e all\u2019estero, sia in ambito Enterprise che PMI, grazie all\u2019efficace metodo <strong>MAKE PROGRESS con gli OKR<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019evento sar\u00e0 condotto da Antonio Civita e Michael Goitein. Entrambi sono tra i membri fondatori della community globale Dreams with Deadlines nella quale leader e innovatori di tutto il mondo, con un comprovato track record nell&#8217;utilizzo efficace degli OKR e delle pratiche agili, si aiutano reciprocamente per raggiungere obiettivi audaci e costruire un futuro migliore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri i risultati del pi\u00f9 grande studio data-driven mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo. Evento in lingua italiana, per le aziende italiane.<\/p>\n","protected":false},"featured_media":21669,"template":"","categories":[18,20,61],"tags":[],"class_list":["post-21526","evento","type-evento","status-publish","has-post-thumbnail","hentry","category-eventi","category-passati","category-strtgy_layout_eventi_v2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo stato dell\u2019arte degli OKR. I risultati del pi\u00f9 grande studio 2023<\/title>\n<meta name=\"description\" content=\"\ud83c\uddee\ud83c\uddf9 In lingua italiana, per le aziende italiane. I risultati del pi\u00f9 grande studio mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo stato dell\u2019arte degli OKR. I risultati del pi\u00f9 grande studio 2023\" \/>\n<meta property=\"og:description\" content=\"Vieni a scoprire i risultati del pi\u00f9 grande studio data-driven mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo. \ud83c\uddee\ud83c\uddf9 Evento in lingua italiana, per le aziende italiane.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/\" \/>\n<meta property=\"og:site_name\" content=\"STRTGY\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/strtgydesign\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-06T05:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/GSOKR-newsletter-02.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1921\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/GSOKR-newsletter-02.png\" \/>\n<meta name=\"twitter:site\" content=\"@antoniocivita\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/\",\"url\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/\",\"name\":\"Lo stato dell\u2019arte degli OKR. I risultati del pi\u00f9 grande studio 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/gsokr-cover.jpg\",\"datePublished\":\"2023-07-17T11:06:14+00:00\",\"dateModified\":\"2023-08-06T05:43:35+00:00\",\"description\":\"\ud83c\uddee\ud83c\uddf9 In lingua italiana, per le aziende italiane. I risultati del pi\u00f9 grande studio mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/gsokr-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/gsokr-cover.jpg\",\"width\":1119,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/evento\\\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/strtgy.design\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Global State of OKRs \u2014 2023 Trends Report \\\/ Edizione Italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/strtgy.design\\\/en\\\/\",\"name\":\"STRTGY\",\"description\":\"Design + Business + Tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/strtgy.design\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#organization\",\"name\":\"STRTGY\",\"url\":\"https:\\\/\\\/strtgy.design\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/STRTGY-Symbol.png\",\"contentUrl\":\"https:\\\/\\\/strtgy.design\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/STRTGY-Symbol.png\",\"width\":160,\"height\":160,\"caption\":\"STRTGY\"},\"image\":{\"@id\":\"https:\\\/\\\/strtgy.design\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/strtgydesign\",\"https:\\\/\\\/x.com\\\/antoniocivita\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/strtgy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo stato dell\u2019arte degli OKR. I risultati del pi\u00f9 grande studio 2023","description":"\ud83c\uddee\ud83c\uddf9 In lingua italiana, per le aziende italiane. I risultati del pi\u00f9 grande studio mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/","og_locale":"en_US","og_type":"article","og_title":"Lo stato dell\u2019arte degli OKR. I risultati del pi\u00f9 grande studio 2023","og_description":"Vieni a scoprire i risultati del pi\u00f9 grande studio data-driven mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo. \ud83c\uddee\ud83c\uddf9 Evento in lingua italiana, per le aziende italiane.","og_url":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/","og_site_name":"STRTGY","article_publisher":"https:\/\/www.facebook.com\/strtgydesign","article_modified_time":"2023-08-06T05:43:35+00:00","og_image":[{"width":1921,"height":1080,"url":"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/GSOKR-newsletter-02.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/GSOKR-newsletter-02.png","twitter_site":"@antoniocivita","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/","url":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/","name":"Lo stato dell\u2019arte degli OKR. I risultati del pi\u00f9 grande studio 2023","isPartOf":{"@id":"https:\/\/strtgy.design\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/#primaryimage"},"image":{"@id":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/gsokr-cover.jpg","datePublished":"2023-07-17T11:06:14+00:00","dateModified":"2023-08-06T05:43:35+00:00","description":"\ud83c\uddee\ud83c\uddf9 In lingua italiana, per le aziende italiane. I risultati del pi\u00f9 grande studio mai condotto sull\u2019utilizzo degli OKR in oltre 400 aziende nel mondo.","breadcrumb":{"@id":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/#primaryimage","url":"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/gsokr-cover.jpg","contentUrl":"https:\/\/strtgy.design\/wp-content\/uploads\/2023\/07\/gsokr-cover.jpg","width":1119,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/strtgy.design\/en\/evento\/the-global-state-of-okrs-2023-trends-report-edizione-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/strtgy.design\/en\/"},{"@type":"ListItem","position":2,"name":"The Global State of OKRs \u2014 2023 Trends Report \/ Edizione Italiana"}]},{"@type":"WebSite","@id":"https:\/\/strtgy.design\/en\/#website","url":"https:\/\/strtgy.design\/en\/","name":"STRTGY","description":"Design + Business + Tech","publisher":{"@id":"https:\/\/strtgy.design\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strtgy.design\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/strtgy.design\/en\/#organization","name":"STRTGY","url":"https:\/\/strtgy.design\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/strtgy.design\/en\/#\/schema\/logo\/image\/","url":"https:\/\/strtgy.design\/wp-content\/uploads\/2024\/04\/STRTGY-Symbol.png","contentUrl":"https:\/\/strtgy.design\/wp-content\/uploads\/2024\/04\/STRTGY-Symbol.png","width":160,"height":160,"caption":"STRTGY"},"image":{"@id":"https:\/\/strtgy.design\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/strtgydesign","https:\/\/x.com\/antoniocivita","https:\/\/www.linkedin.com\/company\/strtgy\/"]}]}},"_links":{"self":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/evento\/21526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/types\/evento"}],"version-history":[{"count":0,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/evento\/21526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/media\/21669"}],"wp:attachment":[{"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/media?parent=21526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/categories?post=21526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strtgy.design\/en\/wp-json\/wp\/v2\/tags?post=21526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}